{"id":1632,"date":"2022-01-14T08:00:00","date_gmt":"2022-01-14T11:00:00","guid":{"rendered":"https:\/\/museuweg.net\/blog\/?p=1632"},"modified":"2026-02-09T15:47:31","modified_gmt":"2026-02-09T18:47:31","slug":"cores-por-que-enxergamos-colorido","status":"publish","type":"post","link":"https:\/\/museuweg.net\/blog\/cores-por-que-enxergamos-colorido\/","title":{"rendered":"Cores: por que enxergamos colorido?"},"content":{"rendered":"\n<p>Um dos principais sentidos do corpo humano, a vis\u00e3o \u00e9 uma das formas mais potentes de percep\u00e7\u00e3o e interpreta\u00e7\u00e3o de tudo o que nos cerca.&nbsp;<\/p>\n\n\n\n<p>As cores e as luzes atraem o nosso olhar, e tudo que est\u00e1 \u00e0 nossa volta parece ser colorido: a natureza, os objetos, as cidades. Mas e se voc\u00ea descobrisse que, na verdade, as cores n\u00e3o existem? Elas s\u00e3o fabricadas pelo nosso c\u00e9rebro.<\/p>\n\n\n\n<p>Isso acontece porque os objetos absorvem as cores que est\u00e3o na luz branca. Quando essa luz reflete nos nossos olhos, na camada chamada de retina, as c\u00e9lulas chamadas de cones e os bastonetes transmitem a informa\u00e7\u00e3o sobre as cores para o nosso c\u00e9rebro.&nbsp;<\/p>\n\n\n\n<p>Por ser um processo individual, cada pessoa percebe as cores de um jeito. Continue a leitura para entender melhor como as cores se formam e<strong> por que enxergamos colorido<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Como as cores se formam<\/strong><\/h2>\n\n\n\n<p>Antes de falarmos sobre como os nossos olhos enxergam as cores, vamos entender como elas se formam.<\/p>\n\n\n\n<p>Quando dizemos que as cores n\u00e3o existem, \u00e9 porque as tonalidades s\u00f3 aparecem na presen\u00e7a da luz branca, que \u00e9 a mistura de v\u00e1rias cores. Sem a luz, n\u00e3o h\u00e1 cor, apenas um espa\u00e7o vazio representado pelo preto.<\/p>\n\n\n\n<p>Ou seja, a cor \u00e9 a impress\u00e3o causada nos olhos pela luz. A cor neutra \u00e9 o branco, ele \u00e9 a uni\u00e3o de todas as cores que podemos enxergar, compostas pelos espectros de vermelho, laranja, amarelo, verde, azul, anil e violeta.&nbsp;<\/p>\n\n\n\n<p>A aus\u00eancia de luz \u2013 ou inexist\u00eancia de cor \u2013 \u00e9 representada pelo preto, j\u00e1 que n\u00e3o consegue refletir luminosidade nos objetos.<\/p>\n\n\n\n<p>Diferenciamos uma tonalidade da outra por meio do fen\u00f4meno f\u00edsico chamado \u201ccomprimento de onda\u201d. Isso quer dizer que as cores s\u00e3o ondas que vibram em velocidades diferentes. Quanto mais r\u00e1pida a onda, mais azulada ela fica; e quanto mais lenta, mais avermelhada.<\/p>\n\n\n\n<p>Quando um feixe de luz toca um objeto colorido, parte desse feixe \u00e9 refletida enquanto parte \u00e9 absorvida pelo objeto, por\u00e9m, s\u00f3 podemos ver a cor correspondente \u00e0 frequ\u00eancia que foi refletida.<\/p>\n\n\n\n<p>Logo, a cor de um objeto \u00e9 justamente a cor que ele n\u00e3o absorveu. Se uma ma\u00e7\u00e3 \u00e9 vermelha, \u00e9 porque ela absorve muito todas as cores, menos a vermelha \u2013 que \u00e9 refletida para o nosso olho.<\/p>\n\n\n\n<figure class=\"wp-block-gallery aligncenter has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"600\" data-id=\"2814\" src=\"https:\/\/museuweg.net\/blog\/wp-content\/uploads\/2023\/03\/Como-as-cores-se-formam.jpg\" alt=\"\" class=\"wp-image-2814\" srcset=\"https:\/\/museuweg.net\/blog\/wp-content\/uploads\/2023\/03\/Como-as-cores-se-formam.jpg 1024w, https:\/\/museuweg.net\/blog\/wp-content\/uploads\/2023\/03\/Como-as-cores-se-formam-300x176.jpg 300w, https:\/\/museuweg.net\/blog\/wp-content\/uploads\/2023\/03\/Como-as-cores-se-formam-768x450.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n<\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Newton e o prisma<\/strong><\/h3>\n\n\n\n<p>A descoberta de que as cores s\u00e3o nada mais que luzes refletidas sobre o branco pode ser um pouco impactante. Imagine ent\u00e3o em 1665 quando Newton apresentou a sua teoria.<\/p>\n\n\n\n<p>Acontece que, por muitos s\u00e9culos, o <a href=\"https:\/\/museuweg.net\/blog\/como-se-forma-o-arco-iris-conheca-algumas-curiosidades-sobre-o-fenomeno\/#content\">arco-\u00edris era um grande mist\u00e9rio da natureza<\/a>. Ningu\u00e9m sabia como ou por que aquele arco colorido surgia. Da mesma forma, o feixe multicolorido que sa\u00eda de dentro dos prismas tamb\u00e9m era um mist\u00e9rio.<\/p>\n\n\n\n<p>O surgimento dessas cores era t\u00e3o misterioso que as pessoas acreditavam serem obras de espectros, como seres fant\u00e1sticos parecidos com fantasmas.<\/p>\n\n\n\n<p>At\u00e9 ent\u00e3o, artistas e cientistas viam o branco como uma cor pura, e n\u00e3o uma mistura de cores. Mas essa concep\u00e7\u00e3o foi alterada pelo cientista ingl\u00eas <a href=\"https:\/\/museuweg.net\/blog\/isaac-newton-curiosidades-sobre-um-dos-maiores-cientistas-de-todos-os-tempos\/#content\">Isaac Newton<\/a>.<\/p>\n\n\n\n<p>Em 1665, Newton fez um experimento que mudaria tudo. Ele dispunha apenas de alguns prismas, lentes e da luz do sol. Atrav\u00e9s de um pequeno furo em uma cortina, o cientista obteve um feixe de luz que fez incidir sobre o prisma.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"600\" src=\"https:\/\/museuweg.net\/blog\/wp-content\/uploads\/2023\/03\/Newton-e-o-prisma.jpg\" alt=\"\" class=\"wp-image-2815\" srcset=\"https:\/\/museuweg.net\/blog\/wp-content\/uploads\/2023\/03\/Newton-e-o-prisma.jpg 1024w, https:\/\/museuweg.net\/blog\/wp-content\/uploads\/2023\/03\/Newton-e-o-prisma-300x176.jpg 300w, https:\/\/museuweg.net\/blog\/wp-content\/uploads\/2023\/03\/Newton-e-o-prisma-768x450.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<p>A luz, depois de passar pelo prisma, projetava sobre a parede uma mancha com as cores distribu\u00eddas do vermelho ao violeta.&nbsp;<\/p>\n\n\n\n<p>Esse feixe colorido foi focado por uma lente e direcionado para um segundo prisma. As cores ent\u00e3o se misturaram, resultando em luz branca.<\/p>\n\n\n\n<p>Para n\u00e3o haver d\u00favidas, o mesmo feixe atravessou um terceiro prisma e novamente se separou nas cores do arco-\u00edris. Essa \u00e9 a prova definitiva de que a luz branca \u00e9 composta por todas as cores.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Como as cores chegam aos nossos olhos<\/strong><\/h2>\n\n\n\n<p>Hora de entender como essa \u201cm\u00e1gica\u201d funciona para os nossos olhos e por que enxergamos colorido.<\/p>\n\n\n\n<p>O caminho que a luz refletida por um objeto percorre no nosso olho \u00e9 o seguinte: ela atravessa a c\u00f3rnea, a \u00edris (respons\u00e1vel por regular a quantidade de luz recebida pela pupila), a pupila, o cristalino e chega at\u00e9 a retina.<\/p>\n\n\n\n<p>\u00c9 dentro da retina que as imagens s\u00e3o formadas, nela, existe uma camada de c\u00e9lulas bem pequenas e sens\u00edveis \u00e0 luz \u2013 os fotorreceptores.&nbsp;<\/p>\n\n\n\n<p>Eles s\u00e3o de dois tipos: bastonetes, que funcionam em lugares mais escuros, e os cones, que se adaptam \u00e0 luz e s\u00e3o respons\u00e1veis pelas cores que enxergamos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Cada um v\u00ea uma cor<\/strong><\/h3>\n\n\n\n<p>Uma cor nunca ser\u00e1 exatamente igual para todas as pessoas. Isso acontece porque as densidades de recep\u00e7\u00e3o da luz variam de um indiv\u00edduo para outro.&nbsp;<\/p>\n\n\n\n<p>\u00c9 o nosso c\u00e9rebro que produz as cores, o que gera varia\u00e7\u00f5es de acordo com cada observador: o azul que voc\u00ea v\u00ea pode n\u00e3o ser a mesma tonalidade de azul que seu amigo v\u00ea.<\/p>\n\n\n\n<p>Al\u00e9m disso, algumas pessoas t\u00eam daltonismo \u2013 um dist\u00farbio da percep\u00e7\u00e3o visual identificado pelo n\u00e3o funcionamento dos cones, os respons\u00e1veis pela diferencia\u00e7\u00e3o das cores.<\/p>\n\n\n\n<p>Logo, o indiv\u00edduo com daltonismo sente dificuldade em apontar a diferen\u00e7a das tonalidades, como tons de vermelho ou laranja. A confus\u00e3o tamb\u00e9m existe entre verde, vermelho, azul e amarelo, que s\u00e3o cores oponentes.&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-center\">***<\/p>\n\n\n\n<p>Agora voc\u00ea j\u00e1 sabe como somos capazes de ver o mundo colorido e que cada pessoa v\u00ea o mundo de um jeitinho. Continue no blog para mais curiosidades! <a href=\"https:\/\/museuweg.net\/blog\/qual-e-a-composicao-da-lua-por-que-ela-muda-de-forma-e-tamanho-conheca-algumas-curiosidades\/#content\">Que tal conhecer um pouco mais sobre a lua?<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ser\u00e1 que as cores realmente existem? <\/p>\n","protected":false},"author":4,"featured_media":2498,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,603],"tags":[818,816,431,821,819,817,822,820],"class_list":["post-1632","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-2","category-curiosidades","tag-como-as-cores-sao-formadas","tag-cores","tag-curiosidades","tag-newton","tag-o-que-sao-cores","tag-por-que-enxergamos-colorido","tag-prisma","tag-visao"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cores: por que enxergamos colorido? - Blog com Ci\u00eancia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/museuweg.net\/blog\/cores-por-que-enxergamos-colorido\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cores: por que enxergamos colorido? - Blog com Ci\u00eancia\" \/>\n<meta property=\"og:description\" content=\"Ser\u00e1 que as cores realmente existem?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/museuweg.net\/blog\/cores-por-que-enxergamos-colorido\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog com Ci\u00eancia\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-14T11:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-09T18:47:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/museuweg.net\/blog\/wp-content\/uploads\/2022\/01\/14-de-janeiro-de-2022.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1106\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"TK Comunica\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"TK Comunica\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/cores-por-que-enxergamos-colorido\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/cores-por-que-enxergamos-colorido\\\/\"},\"author\":{\"name\":\"TK Comunica\u00e7\u00e3o\",\"@id\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/#\\\/schema\\\/person\\\/335af7b18e8e13d0ea182a6959e3cd71\"},\"headline\":\"Cores: por que enxergamos colorido?\",\"datePublished\":\"2022-01-14T11:00:00+00:00\",\"dateModified\":\"2026-02-09T18:47:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/cores-por-que-enxergamos-colorido\\\/\"},\"wordCount\":948,\"image\":{\"@id\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/cores-por-que-enxergamos-colorido\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/14-de-janeiro-de-2022.png\",\"keywords\":[\"como as cores s\u00e3o formadas?\",\"cores\",\"curiosidades\",\"newton\",\"o que s\u00e3o cores?\",\"por que enxergamos colorido?\",\"prisma\",\"vis\u00e3o\"],\"articleSection\":[\"Ci\u00eancia\",\"Curiosidades\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/cores-por-que-enxergamos-colorido\\\/\",\"url\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/cores-por-que-enxergamos-colorido\\\/\",\"name\":\"Cores: por que enxergamos colorido? - Blog com Ci\u00eancia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/cores-por-que-enxergamos-colorido\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/cores-por-que-enxergamos-colorido\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/14-de-janeiro-de-2022.png\",\"datePublished\":\"2022-01-14T11:00:00+00:00\",\"dateModified\":\"2026-02-09T18:47:31+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/#\\\/schema\\\/person\\\/335af7b18e8e13d0ea182a6959e3cd71\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/cores-por-que-enxergamos-colorido\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/museuweg.net\\\/blog\\\/cores-por-que-enxergamos-colorido\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/cores-por-que-enxergamos-colorido\\\/#primaryimage\",\"url\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/14-de-janeiro-de-2022.png\",\"contentUrl\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/14-de-janeiro-de-2022.png\",\"width\":1106,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/cores-por-que-enxergamos-colorido\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cores: por que enxergamos colorido?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/\",\"name\":\"Blog com Ci\u00eancia\",\"description\":\"Museu WEG de Ci\u00eancia e Tecnologia\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/#\\\/schema\\\/person\\\/335af7b18e8e13d0ea182a6959e3cd71\",\"name\":\"TK Comunica\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ebfca77cb195b9e897fac15a333836ddc82752dc4be91c0f419de3d3daf543b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ebfca77cb195b9e897fac15a333836ddc82752dc4be91c0f419de3d3daf543b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ebfca77cb195b9e897fac15a333836ddc82752dc4be91c0f419de3d3daf543b4?s=96&d=mm&r=g\",\"caption\":\"TK Comunica\u00e7\u00e3o\"},\"url\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/author\\\/tkcomunicacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cores: por que enxergamos colorido? - Blog com Ci\u00eancia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/museuweg.net\/blog\/cores-por-que-enxergamos-colorido\/","og_locale":"pt_BR","og_type":"article","og_title":"Cores: por que enxergamos colorido? - Blog com Ci\u00eancia","og_description":"Ser\u00e1 que as cores realmente existem?","og_url":"https:\/\/museuweg.net\/blog\/cores-por-que-enxergamos-colorido\/","og_site_name":"Blog com Ci\u00eancia","article_published_time":"2022-01-14T11:00:00+00:00","article_modified_time":"2026-02-09T18:47:31+00:00","og_image":[{"width":1106,"height":400,"url":"https:\/\/museuweg.net\/blog\/wp-content\/uploads\/2022\/01\/14-de-janeiro-de-2022.png","type":"image\/png"}],"author":"TK Comunica\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"TK Comunica\u00e7\u00e3o","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/museuweg.net\/blog\/cores-por-que-enxergamos-colorido\/#article","isPartOf":{"@id":"https:\/\/museuweg.net\/blog\/cores-por-que-enxergamos-colorido\/"},"author":{"name":"TK Comunica\u00e7\u00e3o","@id":"https:\/\/museuweg.net\/blog\/#\/schema\/person\/335af7b18e8e13d0ea182a6959e3cd71"},"headline":"Cores: por que enxergamos colorido?","datePublished":"2022-01-14T11:00:00+00:00","dateModified":"2026-02-09T18:47:31+00:00","mainEntityOfPage":{"@id":"https:\/\/museuweg.net\/blog\/cores-por-que-enxergamos-colorido\/"},"wordCount":948,"image":{"@id":"https:\/\/museuweg.net\/blog\/cores-por-que-enxergamos-colorido\/#primaryimage"},"thumbnailUrl":"https:\/\/museuweg.net\/blog\/wp-content\/uploads\/2022\/01\/14-de-janeiro-de-2022.png","keywords":["como as cores s\u00e3o formadas?","cores","curiosidades","newton","o que s\u00e3o cores?","por que enxergamos colorido?","prisma","vis\u00e3o"],"articleSection":["Ci\u00eancia","Curiosidades"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/museuweg.net\/blog\/cores-por-que-enxergamos-colorido\/","url":"https:\/\/museuweg.net\/blog\/cores-por-que-enxergamos-colorido\/","name":"Cores: por que enxergamos colorido? - Blog com Ci\u00eancia","isPartOf":{"@id":"https:\/\/museuweg.net\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/museuweg.net\/blog\/cores-por-que-enxergamos-colorido\/#primaryimage"},"image":{"@id":"https:\/\/museuweg.net\/blog\/cores-por-que-enxergamos-colorido\/#primaryimage"},"thumbnailUrl":"https:\/\/museuweg.net\/blog\/wp-content\/uploads\/2022\/01\/14-de-janeiro-de-2022.png","datePublished":"2022-01-14T11:00:00+00:00","dateModified":"2026-02-09T18:47:31+00:00","author":{"@id":"https:\/\/museuweg.net\/blog\/#\/schema\/person\/335af7b18e8e13d0ea182a6959e3cd71"},"breadcrumb":{"@id":"https:\/\/museuweg.net\/blog\/cores-por-que-enxergamos-colorido\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/museuweg.net\/blog\/cores-por-que-enxergamos-colorido\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/museuweg.net\/blog\/cores-por-que-enxergamos-colorido\/#primaryimage","url":"https:\/\/museuweg.net\/blog\/wp-content\/uploads\/2022\/01\/14-de-janeiro-de-2022.png","contentUrl":"https:\/\/museuweg.net\/blog\/wp-content\/uploads\/2022\/01\/14-de-janeiro-de-2022.png","width":1106,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/museuweg.net\/blog\/cores-por-que-enxergamos-colorido\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/museuweg.net\/blog\/"},{"@type":"ListItem","position":2,"name":"Cores: por que enxergamos colorido?"}]},{"@type":"WebSite","@id":"https:\/\/museuweg.net\/blog\/#website","url":"https:\/\/museuweg.net\/blog\/","name":"Blog com Ci\u00eancia","description":"Museu WEG de Ci\u00eancia e Tecnologia","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/museuweg.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/museuweg.net\/blog\/#\/schema\/person\/335af7b18e8e13d0ea182a6959e3cd71","name":"TK Comunica\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/ebfca77cb195b9e897fac15a333836ddc82752dc4be91c0f419de3d3daf543b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ebfca77cb195b9e897fac15a333836ddc82752dc4be91c0f419de3d3daf543b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ebfca77cb195b9e897fac15a333836ddc82752dc4be91c0f419de3d3daf543b4?s=96&d=mm&r=g","caption":"TK Comunica\u00e7\u00e3o"},"url":"https:\/\/museuweg.net\/blog\/author\/tkcomunicacao\/"}]}},"views":38551,"_links":{"self":[{"href":"https:\/\/museuweg.net\/blog\/wp-json\/wp\/v2\/posts\/1632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/museuweg.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/museuweg.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/museuweg.net\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/museuweg.net\/blog\/wp-json\/wp\/v2\/comments?post=1632"}],"version-history":[{"count":3,"href":"https:\/\/museuweg.net\/blog\/wp-json\/wp\/v2\/posts\/1632\/revisions"}],"predecessor-version":[{"id":2816,"href":"https:\/\/museuweg.net\/blog\/wp-json\/wp\/v2\/posts\/1632\/revisions\/2816"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/museuweg.net\/blog\/wp-json\/wp\/v2\/media\/2498"}],"wp:attachment":[{"href":"https:\/\/museuweg.net\/blog\/wp-json\/wp\/v2\/media?parent=1632"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/museuweg.net\/blog\/wp-json\/wp\/v2\/categories?post=1632"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/museuweg.net\/blog\/wp-json\/wp\/v2\/tags?post=1632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}