{"id":1472,"date":"2021-06-13T08:00:00","date_gmt":"2021-06-13T11:00:00","guid":{"rendered":"https:\/\/museuweg.net\/blog\/?p=1472"},"modified":"2026-02-09T15:47:19","modified_gmt":"2026-02-09T18:47:19","slug":"origem-e-curiosidades-sobre-o-forno-micro-ondas","status":"publish","type":"post","link":"https:\/\/museuweg.net\/blog\/origem-e-curiosidades-sobre-o-forno-micro-ondas\/","title":{"rendered":"Origem e curiosidades sobre o forno micro-ondas"},"content":{"rendered":"\n<p>O forno micro-ondas est\u00e1 presente em milhares de resid\u00eancias pelo mundo todo. Simples e pr\u00e1tico, o eletrodom\u00e9stico auxilia a descongelar e aquecer alimentos, sendo o queridinho daqueles que n\u00e3o t\u00eam muito tempo para cozinhar no fog\u00e3o convencional.<\/p>\n\n\n\n<p>Voc\u00ea sabia que a descoberta do princ\u00edpio do forno micro-ondas foi por acaso? Continue lendo para conhecer essa hist\u00f3ria e conferir algumas<strong> curiosidades sobre o forno de micro-ondas<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>A origem do micro-ondas&nbsp;<\/strong><\/h2>\n\n\n\n<p><a href=\"https:\/\/museuweg.net\/blog\/seis-descobertas-da-ciencia-que-aconteceram-por-acaso\/#content\">O forno de micro-ondas surgiu por um mero acaso<\/a>. Durante a Segunda Guerra Mundial, micro-ondas eletromagn\u00e9ticas eram produzidas por um magnetron (uma v\u00e1lvula eletr\u00f4nica que funciona como um oscilador na faixa de micro-ondas) com a inten\u00e7\u00e3o de detectar avi\u00f5es inimigos.&nbsp;<\/p>\n\n\n\n<p>Por volta de 1946, nos Estados Unidos, o engenheiro eletr\u00f4nico Percy Spencer,&nbsp;<\/p>\n\n\n\n<p>que trabalhava em uma empresa fabricando magnetrons para esses aparelhos de radar, colocou uma barra de chocolate no bolso da cal\u00e7a e foi trabalhar.<\/p>\n\n\n\n<p>Enquanto trabalhava em um aparelho de radar ativo, ele percebeu que a barra que estava no bolso da sua cal\u00e7a havia derretido. Spencer sabia que as micro-ondas geravam calor, logo, sup\u00f4s que essas ondas escaparam do tubo de magnetron, atingiram e derreteram a barra de chocolate.<\/p>\n\n\n\n<p>Intrigado com o fato, ele resolveu fazer um experimento. Comprou milho de pipoca e colocou o pacote na frente do tubo de magnetron; em poucos instantes, as pipocas come\u00e7aram a estourar.&nbsp;<\/p>\n\n\n\n<p>Spencer ainda resolveu fazer um novo experimento. Colocou um ovo cru dentro de um pote com um buraco e deixou-o voltado para o tubo de magnetron. O resultado foi a explos\u00e3o do ovo. Sua conclus\u00e3o foi que o ovo cozinhou de dentro para fora e estourou em raz\u00e3o da press\u00e3o.<\/p>\n\n\n\n<p>Naquela \u00e9poca, o magnetron j\u00e1 estava muito desenvolvido. Ao perceber que poderia fazer a mesma coisa com outros alimentos, Spencer tratou de fazer com que se pudesse obter o m\u00e1ximo de proveito das micro-ondas.&nbsp;<\/p>\n\n\n\n<p>Ap\u00f3s diversos experimentos, Spencer obteve, em 1946, a primeira patente para uso das micro-ondas para efeitos culin\u00e1rios. Logo, em 1947, a Raytheon produziu e comercializou o primeiro forno micro-ondas da hist\u00f3ria. Ele media 1,8 metros de altura e pesava 340 kg, sendo essa uma das<strong> curiosidades sobre o forno de micro-ondas<\/strong>.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"600\" src=\"https:\/\/museuweg.net\/blog\/wp-content\/uploads\/2023\/03\/Como-funciona-o-micro-ondas.jpg\" alt=\"\" class=\"wp-image-2720\" title=\"Percy LeBaron Spencer\" srcset=\"https:\/\/museuweg.net\/blog\/wp-content\/uploads\/2023\/03\/Como-funciona-o-micro-ondas.jpg 1024w, https:\/\/museuweg.net\/blog\/wp-content\/uploads\/2023\/03\/Como-funciona-o-micro-ondas-300x176.jpg 300w, https:\/\/museuweg.net\/blog\/wp-content\/uploads\/2023\/03\/Como-funciona-o-micro-ondas-768x450.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<p>No entanto, foi s\u00f3 a partir de 1975 que a inven\u00e7\u00e3o come\u00e7ou a \u201cinvadir\u201d os ambientes dom\u00e9sticos, revolucionando o modo de cozinhar, essencialmente em termos de rapidez e poupan\u00e7a de energia (quando comparado aos fornos el\u00e9tricos), sendo uma grande contribui\u00e7\u00e3o para a sociedade atual.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Como funciona o micro-ondas?<\/strong><\/h2>\n\n\n\n<p>O aquecimento do forno micro-ondas ocorre em raz\u00e3o de uma radia\u00e7\u00e3o eletromagn\u00e9tica de 2.450 MHz, gerada por um magnetron e irradiada por um ventilador de metal, localizado na parte superior do aparelho.<\/p>\n\n\n\n<p>Essa \u00e9 a mesma frequ\u00eancia de resson\u00e2ncia das mol\u00e9culas de \u00e1gua. Quando o forno \u00e9 utilizado, a radia\u00e7\u00e3o aumenta a agita\u00e7\u00e3o das mol\u00e9culas assim\u00e9tricas da \u00e1gua, \u00f3leos e a\u00e7\u00facares dos alimentos, e as ondas s\u00e3o refletidas v\u00e1rias vezes nas paredes met\u00e1licas sobre os alimentos, aquecendo-os de modo quase uniforme.<\/p>\n\n\n\n<p>Por agitar as mol\u00e9culas de \u00e1gua e de gordura das camadas mais externas com mais intensidade que as camadas mais internas do alimento, aquece os produtos de fora para dentro.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Tr\u00eas curiosidades sobre o micro-ondas&nbsp;<\/strong><\/h3>\n\n\n\n<p>1. O micro-ondas inventado por Spencer produzia 3.000 watts, <a href=\"https:\/\/museuweg.net\/blog\/voce-sabe-como-escolher-aparelhos-que-consomem-menos-energia\/#content\">cerca de tr\u00eas vezes a quantidade de radia\u00e7\u00e3o produzida por fornos de micro-ondas atuais<\/a>.<\/p>\n\n\n\n<p>2. O magnetron do primeiro micro-ondas precisava ser resfriado por meio de \u00e1gua, o que obrigava o produto a ter uma liga\u00e7\u00e3o com \u00e1gua canalizada.<\/p>\n\n\n\n<p>3. A seguran\u00e7a \u00e9 garantida porque as micro-ondas n\u00e3o s\u00e3o nucleares, pertencendo ao mesmo tipo de ondas do r\u00e1dio ou mesmo da luz, s\u00f3 que em menor tamanho.<\/p>\n\n\n\n<p>Incr\u00edvel descobrir a hist\u00f3ria por tr\u00e1s de algo t\u00e3o comum no nosso dia a dia, n\u00e3o \u00e9? Agora que voc\u00ea j\u00e1 sabe como \u00e9 poss\u00edvel esquentar seu lanche no micro-ondas e como essa descoberta aconteceu por acaso, que tal descobrir <a href=\"https:\/\/museuweg.net\/blog\/como-seria-o-mundo-sem-eletricidade\/#content\">como seria o mundo sem eletricidade?<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Confira a hist\u00f3ria e algumas curiosidades sobre o forno de micro-ondas.<\/p>\n","protected":false},"author":4,"featured_media":2305,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[603,3,21],"tags":[705,703,704,701,702],"class_list":["post-1472","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades","category-eletricidade","category-tecnologia-2","tag-curiosidades-sobre-o-microondas","tag-forno-microondas","tag-historia-do-microondas","tag-microondas","tag-origem"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Origem e curiosidades sobre o forno micro-ondas - Blog com Ci\u00eancia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/museuweg.net\/blog\/origem-e-curiosidades-sobre-o-forno-micro-ondas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Origem e curiosidades sobre o forno micro-ondas - Blog com Ci\u00eancia\" \/>\n<meta property=\"og:description\" content=\"Confira a hist\u00f3ria e algumas curiosidades sobre o forno de micro-ondas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/museuweg.net\/blog\/origem-e-curiosidades-sobre-o-forno-micro-ondas\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog com Ci\u00eancia\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-13T11:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-09T18:47:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/museuweg.net\/blog\/wp-content\/uploads\/2021\/06\/13-de-junho-de-2021.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1106\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"TK Comunica\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"TK Comunica\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/origem-e-curiosidades-sobre-o-forno-micro-ondas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/origem-e-curiosidades-sobre-o-forno-micro-ondas\\\/\"},\"author\":{\"name\":\"TK Comunica\u00e7\u00e3o\",\"@id\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/#\\\/schema\\\/person\\\/335af7b18e8e13d0ea182a6959e3cd71\"},\"headline\":\"Origem e curiosidades sobre o forno micro-ondas\",\"datePublished\":\"2021-06-13T11:00:00+00:00\",\"dateModified\":\"2026-02-09T18:47:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/origem-e-curiosidades-sobre-o-forno-micro-ondas\\\/\"},\"wordCount\":701,\"image\":{\"@id\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/origem-e-curiosidades-sobre-o-forno-micro-ondas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/13-de-junho-de-2021.png\",\"keywords\":[\"curiosidades sobre o microondas\",\"forno microondas\",\"hist\u00f3ria do microondas\",\"microondas\",\"origem\"],\"articleSection\":[\"Curiosidades\",\"Eletricidade\",\"Tecnologia\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/origem-e-curiosidades-sobre-o-forno-micro-ondas\\\/\",\"url\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/origem-e-curiosidades-sobre-o-forno-micro-ondas\\\/\",\"name\":\"Origem e curiosidades sobre o forno micro-ondas - Blog com Ci\u00eancia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/origem-e-curiosidades-sobre-o-forno-micro-ondas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/origem-e-curiosidades-sobre-o-forno-micro-ondas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/13-de-junho-de-2021.png\",\"datePublished\":\"2021-06-13T11:00:00+00:00\",\"dateModified\":\"2026-02-09T18:47:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/#\\\/schema\\\/person\\\/335af7b18e8e13d0ea182a6959e3cd71\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/origem-e-curiosidades-sobre-o-forno-micro-ondas\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/museuweg.net\\\/blog\\\/origem-e-curiosidades-sobre-o-forno-micro-ondas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/origem-e-curiosidades-sobre-o-forno-micro-ondas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/13-de-junho-de-2021.png\",\"contentUrl\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/13-de-junho-de-2021.png\",\"width\":1106,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/origem-e-curiosidades-sobre-o-forno-micro-ondas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Origem e curiosidades sobre o forno micro-ondas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/\",\"name\":\"Blog com Ci\u00eancia\",\"description\":\"Museu WEG de Ci\u00eancia e Tecnologia\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/#\\\/schema\\\/person\\\/335af7b18e8e13d0ea182a6959e3cd71\",\"name\":\"TK Comunica\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ebfca77cb195b9e897fac15a333836ddc82752dc4be91c0f419de3d3daf543b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ebfca77cb195b9e897fac15a333836ddc82752dc4be91c0f419de3d3daf543b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ebfca77cb195b9e897fac15a333836ddc82752dc4be91c0f419de3d3daf543b4?s=96&d=mm&r=g\",\"caption\":\"TK Comunica\u00e7\u00e3o\"},\"url\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/author\\\/tkcomunicacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Origem e curiosidades sobre o forno micro-ondas - Blog com Ci\u00eancia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/museuweg.net\/blog\/origem-e-curiosidades-sobre-o-forno-micro-ondas\/","og_locale":"pt_BR","og_type":"article","og_title":"Origem e curiosidades sobre o forno micro-ondas - Blog com Ci\u00eancia","og_description":"Confira a hist\u00f3ria e algumas curiosidades sobre o forno de micro-ondas.","og_url":"https:\/\/museuweg.net\/blog\/origem-e-curiosidades-sobre-o-forno-micro-ondas\/","og_site_name":"Blog com Ci\u00eancia","article_published_time":"2021-06-13T11:00:00+00:00","article_modified_time":"2026-02-09T18:47:19+00:00","og_image":[{"width":1106,"height":400,"url":"https:\/\/museuweg.net\/blog\/wp-content\/uploads\/2021\/06\/13-de-junho-de-2021.png","type":"image\/png"}],"author":"TK Comunica\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"TK Comunica\u00e7\u00e3o","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/museuweg.net\/blog\/origem-e-curiosidades-sobre-o-forno-micro-ondas\/#article","isPartOf":{"@id":"https:\/\/museuweg.net\/blog\/origem-e-curiosidades-sobre-o-forno-micro-ondas\/"},"author":{"name":"TK Comunica\u00e7\u00e3o","@id":"https:\/\/museuweg.net\/blog\/#\/schema\/person\/335af7b18e8e13d0ea182a6959e3cd71"},"headline":"Origem e curiosidades sobre o forno micro-ondas","datePublished":"2021-06-13T11:00:00+00:00","dateModified":"2026-02-09T18:47:19+00:00","mainEntityOfPage":{"@id":"https:\/\/museuweg.net\/blog\/origem-e-curiosidades-sobre-o-forno-micro-ondas\/"},"wordCount":701,"image":{"@id":"https:\/\/museuweg.net\/blog\/origem-e-curiosidades-sobre-o-forno-micro-ondas\/#primaryimage"},"thumbnailUrl":"https:\/\/museuweg.net\/blog\/wp-content\/uploads\/2021\/06\/13-de-junho-de-2021.png","keywords":["curiosidades sobre o microondas","forno microondas","hist\u00f3ria do microondas","microondas","origem"],"articleSection":["Curiosidades","Eletricidade","Tecnologia"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/museuweg.net\/blog\/origem-e-curiosidades-sobre-o-forno-micro-ondas\/","url":"https:\/\/museuweg.net\/blog\/origem-e-curiosidades-sobre-o-forno-micro-ondas\/","name":"Origem e curiosidades sobre o forno micro-ondas - Blog com Ci\u00eancia","isPartOf":{"@id":"https:\/\/museuweg.net\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/museuweg.net\/blog\/origem-e-curiosidades-sobre-o-forno-micro-ondas\/#primaryimage"},"image":{"@id":"https:\/\/museuweg.net\/blog\/origem-e-curiosidades-sobre-o-forno-micro-ondas\/#primaryimage"},"thumbnailUrl":"https:\/\/museuweg.net\/blog\/wp-content\/uploads\/2021\/06\/13-de-junho-de-2021.png","datePublished":"2021-06-13T11:00:00+00:00","dateModified":"2026-02-09T18:47:19+00:00","author":{"@id":"https:\/\/museuweg.net\/blog\/#\/schema\/person\/335af7b18e8e13d0ea182a6959e3cd71"},"breadcrumb":{"@id":"https:\/\/museuweg.net\/blog\/origem-e-curiosidades-sobre-o-forno-micro-ondas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/museuweg.net\/blog\/origem-e-curiosidades-sobre-o-forno-micro-ondas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/museuweg.net\/blog\/origem-e-curiosidades-sobre-o-forno-micro-ondas\/#primaryimage","url":"https:\/\/museuweg.net\/blog\/wp-content\/uploads\/2021\/06\/13-de-junho-de-2021.png","contentUrl":"https:\/\/museuweg.net\/blog\/wp-content\/uploads\/2021\/06\/13-de-junho-de-2021.png","width":1106,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/museuweg.net\/blog\/origem-e-curiosidades-sobre-o-forno-micro-ondas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/museuweg.net\/blog\/"},{"@type":"ListItem","position":2,"name":"Origem e curiosidades sobre o forno micro-ondas"}]},{"@type":"WebSite","@id":"https:\/\/museuweg.net\/blog\/#website","url":"https:\/\/museuweg.net\/blog\/","name":"Blog com Ci\u00eancia","description":"Museu WEG de Ci\u00eancia e Tecnologia","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/museuweg.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/museuweg.net\/blog\/#\/schema\/person\/335af7b18e8e13d0ea182a6959e3cd71","name":"TK Comunica\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/ebfca77cb195b9e897fac15a333836ddc82752dc4be91c0f419de3d3daf543b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ebfca77cb195b9e897fac15a333836ddc82752dc4be91c0f419de3d3daf543b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ebfca77cb195b9e897fac15a333836ddc82752dc4be91c0f419de3d3daf543b4?s=96&d=mm&r=g","caption":"TK Comunica\u00e7\u00e3o"},"url":"https:\/\/museuweg.net\/blog\/author\/tkcomunicacao\/"}]}},"views":96596,"_links":{"self":[{"href":"https:\/\/museuweg.net\/blog\/wp-json\/wp\/v2\/posts\/1472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/museuweg.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/museuweg.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/museuweg.net\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/museuweg.net\/blog\/wp-json\/wp\/v2\/comments?post=1472"}],"version-history":[{"count":3,"href":"https:\/\/museuweg.net\/blog\/wp-json\/wp\/v2\/posts\/1472\/revisions"}],"predecessor-version":[{"id":2721,"href":"https:\/\/museuweg.net\/blog\/wp-json\/wp\/v2\/posts\/1472\/revisions\/2721"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/museuweg.net\/blog\/wp-json\/wp\/v2\/media\/2305"}],"wp:attachment":[{"href":"https:\/\/museuweg.net\/blog\/wp-json\/wp\/v2\/media?parent=1472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/museuweg.net\/blog\/wp-json\/wp\/v2\/categories?post=1472"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/museuweg.net\/blog\/wp-json\/wp\/v2\/tags?post=1472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}