{"id":1343,"date":"2020-11-11T11:25:03","date_gmt":"2020-11-11T14:25:03","guid":{"rendered":"https:\/\/museuweg.net\/blog\/?p=1343"},"modified":"2026-02-09T15:46:51","modified_gmt":"2026-02-09T18:46:51","slug":"catalogacao-de-documentos-no-museu-weg-premio-elisabete-anderle","status":"publish","type":"post","link":"https:\/\/museuweg.net\/blog\/catalogacao-de-documentos-no-museu-weg-premio-elisabete-anderle\/","title":{"rendered":"Cataloga\u00e7\u00e3o de documentos no Museu WEG \u2013 Pr\u00eamio Elisabete Anderle"},"content":{"rendered":"\n<p>No ano em que comemorou 40 anos de cria\u00e7\u00e3o, a Funda\u00e7\u00e3o Catarinense de Cultura (FCC) lan\u00e7ou o Pr\u00eamio Elisabete Anderle de Est\u00edmulo \u00e0 Cultura que contemplou projetos de tr\u00eas \u00e1reas: Patrim\u00f4nio Cultural, Artes e Artes Populares. Os projetos passaram por an\u00e1lise, avalia\u00e7\u00e3o, classifica\u00e7\u00e3o e sele\u00e7\u00e3o por uma comiss\u00e3o especialmente montada para este fim \u2013 e os ganhadores receberam recursos do Governo do Estado de Santa Catarina. Entre os projetos vencedores est\u00e1 a <strong>cataloga\u00e7\u00e3o de documentos do Museu WEG<\/strong>, que j\u00e1 est\u00e1 com as atividades propostas em andamento. Acompanhe!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Participa\u00e7\u00e3o do Museu WEG no Pr\u00eamio Elisabete Anderle<\/strong><\/h2>\n\n\n\n<p>Sendo o \u00fanico museu de ci\u00eancia e tecnologia de Santa Catarina, o Museu WEG tem um grande acervo que conta a evolu\u00e7\u00e3o tecnol\u00f3gica dos motores el\u00e9tricos: um equipamento que est\u00e1 intrinsecamente correlacionado com a vida das pessoas. Al\u00e9m disso, tamb\u00e9m conta a hist\u00f3ria dos quase 60 anos da WEG, uma multinacional brasileira presente nos 5 continentes, com f\u00e1bricas em mais de 20 pa\u00edses e que emprega mais de 30 mil pessoas no mundo todo.<\/p>\n\n\n\n<p>Estes aspectos tornam seu acervo valioso e mostram o desenvolvimento da ind\u00fastria catarinense e da cidade de Jaragu\u00e1 do Sul e regi\u00e3o. O objetivo do projeto inscrito no Pr\u00eamio Elisabete Anderle foi trabalhar na salvaguarda do acervo documental do museu, que expressa de forma escrita toda a trajet\u00f3ria de empreendedorismo, governan\u00e7a corporativa, inova\u00e7\u00e3o e qualidade da empresa. Dessa forma, foi proposta a realiza\u00e7\u00e3o da classifica\u00e7\u00e3o, cataloga\u00e7\u00e3o, digitaliza\u00e7\u00e3o, higieniza\u00e7\u00e3o, poss\u00edveis restauros e acondicionamento do acervo. Assim, ele poder\u00e1 ser disponibilizado para pesquisa sobre a hist\u00f3ria e desenvolvimento social da regi\u00e3o e na busca de conhecimentos t\u00e9cnicos, al\u00e9m de assegurar sua preserva\u00e7\u00e3o.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>O andamento da cataloga\u00e7\u00e3o<\/strong><\/h2>\n\n\n\n<p>A cataloga\u00e7\u00e3o est\u00e1 ocorrendo sob supervis\u00e3o de uma muse\u00f3logo respons\u00e1vel, a Fernanda Sasse e a atua\u00e7\u00e3o de estagi\u00e1rios \u2013 Luigi Ferraza Maiochi e Higor Azevedo, estudantes da \u00faltima fase do curso de Qu\u00edmica do IFSC \u2013 sob coordena\u00e7\u00e3o da equipe t\u00e9cnica do museu, as atividades iniciaram em setembro de 2020 e levar\u00e3o 6 meses para ficarem prontas.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/lh5.googleusercontent.com\/f10zW2hpFHWcQlTU525eoTekGCv1W_gr_FueOUxMeQX47nHnGyHnEgewo5-FOsWhj6coQUjncIi873vjbE5dtVlDGPz-Q6kShFCf89WV5hi4cHbmkFC-pkd4stbf3P0FUKhxB_Mi\" alt=\"\"\/><figcaption><em>Cataloga\u00e7\u00e3o de documentos no Museu WEG \u2013 Pr\u00eamio Elisabete Anderle<\/em><\/figcaption><\/figure>\n\n\n\n<p>Na primeira semana, os estagi\u00e1rios tiveram capacita\u00e7\u00e3o da \u00e1rea museol\u00f3gica para entenderem os aspectos de conserva\u00e7\u00e3o e arquivamento:<\/p>\n\n\n\n<p>&#8211; Visitaram o arquivo p\u00fablico de Jaragu\u00e1 do Sul com a historiadora Silvia Kita;<\/p>\n\n\n\n<p>&#8211; Conheceram as defini\u00e7\u00f5es e metodologia de cataloga\u00e7\u00e3o e conserva\u00e7\u00e3o de documentos com a muse\u00f3loga Fernanda Sasse;<\/p>\n\n\n\n<p>&#8211; Participaram de reuni\u00f5es online com o tema \u201cO papel do profissional qu\u00edmico na conserva\u00e7\u00e3o de acervos\u201d, com Dr. Thiago Costa, Qu\u00edmico e pesquisador ATECOR. E tamb\u00e9m sobre \u201cConserva\u00e7\u00e3o de Acervos em Papel\u201d, com M\u00e1rcia Escorteganha, Msc Conservadora e Restauradora.<\/p>\n\n\n\n<p>Com acompanhamento da coordenadora do projeto e conservadora do Museu WEG, Gabriella Eger Lux, todo o acervo documental j\u00e1 foi selecionado e dividido por categorias. Agora, todo o acervo est\u00e1 recebendo o diagn\u00f3stico do estado de conserva\u00e7\u00e3o, sendo higienizado (e em alguns casos recebendo restauro curativo), passando pelo processo de digitaliza\u00e7\u00e3o e sendo catalogado em um software de gerenciamento de acervos. Desta forma, ele fica acondicionado em caixas de papel neutro e fica salvaguardado na reserva t\u00e9cnica, que possui temperatura e umidade controlada.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/lh5.googleusercontent.com\/B2IUNiHLHcDqub-dMwOXtzwDFjceuG4Ok2J5eQlNrufSxdOk9gnlqLjSg9PCsndi3hB5zyHkDeAF-dyN7vdyQsxJL5tWI-fTNFrZ-pmLs8ROZ4wsbfIZ5GdAwLFF6CpXwkvovUv7\" alt=\"\"\/><figcaption><em>Cataloga\u00e7\u00e3o e conserva\u00e7\u00e3o de documentos no Museu WEG \u2013 Pr\u00eamio Elisabete Anderle<\/em><\/figcaption><\/figure>\n\n\n\n<p>\u00c9 incr\u00edvel ver toda essa hist\u00f3ria sendo preservada para que mais pessoas possam ter acesso \u00e0 informa\u00e7\u00e3o. Nosso agradecimento \u00e0 Funda\u00e7\u00e3o Catarinense de Cultura por tornar isso poss\u00edvel. Juntos, constru\u00edmos, asseguramos e compartilhamos com a popula\u00e7\u00e3o uma hist\u00f3ria valiosa.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Capela de Higieniza\u00e7\u00e3o dispon\u00edvel<\/strong><\/h2>\n\n\n\n<p>Atrav\u00e9s do projeto, foi poss\u00edvel fazer a aquisi\u00e7\u00e3o de uma Capela de Higieniza\u00e7\u00e3o. Este equipamento \u00e9 de suma import\u00e2ncia  a para higieniza\u00e7\u00e3o manual dos documentos e pe\u00e7as, que torna esta atividade mais t\u00e9cnica, profissional e segura, uma vez que os acervos acumulam poeira e ouras sugidades e a mesa aspira as impurezas eliminadas. <\/p>\n\n\n\n<p>Desta forma, o Museu WEG deixa a disposi\u00e7\u00e3o este equipamento e seu laborat\u00f3rio para os museus que precisarem realizar alguma interven\u00e7\u00e3o em suas cole\u00e7\u00f5es. Para utilizar, basta agendar previamente atrav\u00e9s do telefone (47) 3276-4550 ou pelo e-mail museu@weg.net .<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Todo o acervo est\u00e1 recebendo o diagn\u00f3stico do estado de conserva\u00e7\u00e3o, sendo higienizado e passando pelo processo de digitaliza\u00e7\u00e3o.<\/p>\n","protected":false},"author":4,"featured_media":1578,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[602,599,601,22,600,72],"class_list":["post-1343","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-weg","tag-catalogacao","tag-catalogacao-de-documentos","tag-estimulo-a-cultura","tag-museu-weg","tag-premio-elisabete-anderle","tag-santa-catarina"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cataloga\u00e7\u00e3o de documentos no Museu WEG \u2013 Pr\u00eamio Elisabete Anderle - Blog com Ci\u00eancia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/museuweg.net\/blog\/catalogacao-de-documentos-no-museu-weg-premio-elisabete-anderle\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cataloga\u00e7\u00e3o de documentos no Museu WEG \u2013 Pr\u00eamio Elisabete Anderle - Blog com Ci\u00eancia\" \/>\n<meta property=\"og:description\" content=\"Todo o acervo est\u00e1 recebendo o diagn\u00f3stico do estado de conserva\u00e7\u00e3o, sendo higienizado e passando pelo processo de digitaliza\u00e7\u00e3o.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/museuweg.net\/blog\/catalogacao-de-documentos-no-museu-weg-premio-elisabete-anderle\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog com Ci\u00eancia\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-11T14:25:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-09T18:46:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/museuweg.net\/blog\/wp-content\/uploads\/2020\/11\/Catalog.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1100\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"TK Comunica\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"TK Comunica\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/catalogacao-de-documentos-no-museu-weg-premio-elisabete-anderle\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/catalogacao-de-documentos-no-museu-weg-premio-elisabete-anderle\\\/\"},\"author\":{\"name\":\"TK Comunica\u00e7\u00e3o\",\"@id\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/#\\\/schema\\\/person\\\/335af7b18e8e13d0ea182a6959e3cd71\"},\"headline\":\"Cataloga\u00e7\u00e3o de documentos no Museu WEG \u2013 Pr\u00eamio Elisabete Anderle\",\"datePublished\":\"2020-11-11T14:25:03+00:00\",\"dateModified\":\"2026-02-09T18:46:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/catalogacao-de-documentos-no-museu-weg-premio-elisabete-anderle\\\/\"},\"wordCount\":755,\"image\":{\"@id\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/catalogacao-de-documentos-no-museu-weg-premio-elisabete-anderle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Catalog.png\",\"keywords\":[\"cataloga\u00e7\u00e3o\",\"cataloga\u00e7\u00e3o de documentos\",\"est\u00edmulo \u00e0 cultura\",\"museu weg\",\"pr\u00eamio elisabete anderle\",\"santa catarina\"],\"articleSection\":[\"Museu WEG\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/catalogacao-de-documentos-no-museu-weg-premio-elisabete-anderle\\\/\",\"url\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/catalogacao-de-documentos-no-museu-weg-premio-elisabete-anderle\\\/\",\"name\":\"Cataloga\u00e7\u00e3o de documentos no Museu WEG \u2013 Pr\u00eamio Elisabete Anderle - Blog com Ci\u00eancia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/catalogacao-de-documentos-no-museu-weg-premio-elisabete-anderle\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/catalogacao-de-documentos-no-museu-weg-premio-elisabete-anderle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Catalog.png\",\"datePublished\":\"2020-11-11T14:25:03+00:00\",\"dateModified\":\"2026-02-09T18:46:51+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/#\\\/schema\\\/person\\\/335af7b18e8e13d0ea182a6959e3cd71\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/catalogacao-de-documentos-no-museu-weg-premio-elisabete-anderle\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/museuweg.net\\\/blog\\\/catalogacao-de-documentos-no-museu-weg-premio-elisabete-anderle\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/catalogacao-de-documentos-no-museu-weg-premio-elisabete-anderle\\\/#primaryimage\",\"url\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Catalog.png\",\"contentUrl\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Catalog.png\",\"width\":1100,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/catalogacao-de-documentos-no-museu-weg-premio-elisabete-anderle\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cataloga\u00e7\u00e3o de documentos no Museu WEG \u2013 Pr\u00eamio Elisabete Anderle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/\",\"name\":\"Blog com Ci\u00eancia\",\"description\":\"Museu WEG de Ci\u00eancia e Tecnologia\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/#\\\/schema\\\/person\\\/335af7b18e8e13d0ea182a6959e3cd71\",\"name\":\"TK Comunica\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ebfca77cb195b9e897fac15a333836ddc82752dc4be91c0f419de3d3daf543b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ebfca77cb195b9e897fac15a333836ddc82752dc4be91c0f419de3d3daf543b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ebfca77cb195b9e897fac15a333836ddc82752dc4be91c0f419de3d3daf543b4?s=96&d=mm&r=g\",\"caption\":\"TK Comunica\u00e7\u00e3o\"},\"url\":\"https:\\\/\\\/museuweg.net\\\/blog\\\/author\\\/tkcomunicacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cataloga\u00e7\u00e3o de documentos no Museu WEG \u2013 Pr\u00eamio Elisabete Anderle - Blog com Ci\u00eancia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/museuweg.net\/blog\/catalogacao-de-documentos-no-museu-weg-premio-elisabete-anderle\/","og_locale":"pt_BR","og_type":"article","og_title":"Cataloga\u00e7\u00e3o de documentos no Museu WEG \u2013 Pr\u00eamio Elisabete Anderle - Blog com Ci\u00eancia","og_description":"Todo o acervo est\u00e1 recebendo o diagn\u00f3stico do estado de conserva\u00e7\u00e3o, sendo higienizado e passando pelo processo de digitaliza\u00e7\u00e3o.","og_url":"https:\/\/museuweg.net\/blog\/catalogacao-de-documentos-no-museu-weg-premio-elisabete-anderle\/","og_site_name":"Blog com Ci\u00eancia","article_published_time":"2020-11-11T14:25:03+00:00","article_modified_time":"2026-02-09T18:46:51+00:00","og_image":[{"width":1100,"height":400,"url":"https:\/\/museuweg.net\/blog\/wp-content\/uploads\/2020\/11\/Catalog.png","type":"image\/png"}],"author":"TK Comunica\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"TK Comunica\u00e7\u00e3o","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/museuweg.net\/blog\/catalogacao-de-documentos-no-museu-weg-premio-elisabete-anderle\/#article","isPartOf":{"@id":"https:\/\/museuweg.net\/blog\/catalogacao-de-documentos-no-museu-weg-premio-elisabete-anderle\/"},"author":{"name":"TK Comunica\u00e7\u00e3o","@id":"https:\/\/museuweg.net\/blog\/#\/schema\/person\/335af7b18e8e13d0ea182a6959e3cd71"},"headline":"Cataloga\u00e7\u00e3o de documentos no Museu WEG \u2013 Pr\u00eamio Elisabete Anderle","datePublished":"2020-11-11T14:25:03+00:00","dateModified":"2026-02-09T18:46:51+00:00","mainEntityOfPage":{"@id":"https:\/\/museuweg.net\/blog\/catalogacao-de-documentos-no-museu-weg-premio-elisabete-anderle\/"},"wordCount":755,"image":{"@id":"https:\/\/museuweg.net\/blog\/catalogacao-de-documentos-no-museu-weg-premio-elisabete-anderle\/#primaryimage"},"thumbnailUrl":"https:\/\/museuweg.net\/blog\/wp-content\/uploads\/2020\/11\/Catalog.png","keywords":["cataloga\u00e7\u00e3o","cataloga\u00e7\u00e3o de documentos","est\u00edmulo \u00e0 cultura","museu weg","pr\u00eamio elisabete anderle","santa catarina"],"articleSection":["Museu WEG"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/museuweg.net\/blog\/catalogacao-de-documentos-no-museu-weg-premio-elisabete-anderle\/","url":"https:\/\/museuweg.net\/blog\/catalogacao-de-documentos-no-museu-weg-premio-elisabete-anderle\/","name":"Cataloga\u00e7\u00e3o de documentos no Museu WEG \u2013 Pr\u00eamio Elisabete Anderle - Blog com Ci\u00eancia","isPartOf":{"@id":"https:\/\/museuweg.net\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/museuweg.net\/blog\/catalogacao-de-documentos-no-museu-weg-premio-elisabete-anderle\/#primaryimage"},"image":{"@id":"https:\/\/museuweg.net\/blog\/catalogacao-de-documentos-no-museu-weg-premio-elisabete-anderle\/#primaryimage"},"thumbnailUrl":"https:\/\/museuweg.net\/blog\/wp-content\/uploads\/2020\/11\/Catalog.png","datePublished":"2020-11-11T14:25:03+00:00","dateModified":"2026-02-09T18:46:51+00:00","author":{"@id":"https:\/\/museuweg.net\/blog\/#\/schema\/person\/335af7b18e8e13d0ea182a6959e3cd71"},"breadcrumb":{"@id":"https:\/\/museuweg.net\/blog\/catalogacao-de-documentos-no-museu-weg-premio-elisabete-anderle\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/museuweg.net\/blog\/catalogacao-de-documentos-no-museu-weg-premio-elisabete-anderle\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/museuweg.net\/blog\/catalogacao-de-documentos-no-museu-weg-premio-elisabete-anderle\/#primaryimage","url":"https:\/\/museuweg.net\/blog\/wp-content\/uploads\/2020\/11\/Catalog.png","contentUrl":"https:\/\/museuweg.net\/blog\/wp-content\/uploads\/2020\/11\/Catalog.png","width":1100,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/museuweg.net\/blog\/catalogacao-de-documentos-no-museu-weg-premio-elisabete-anderle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/museuweg.net\/blog\/"},{"@type":"ListItem","position":2,"name":"Cataloga\u00e7\u00e3o de documentos no Museu WEG \u2013 Pr\u00eamio Elisabete Anderle"}]},{"@type":"WebSite","@id":"https:\/\/museuweg.net\/blog\/#website","url":"https:\/\/museuweg.net\/blog\/","name":"Blog com Ci\u00eancia","description":"Museu WEG de Ci\u00eancia e Tecnologia","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/museuweg.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/museuweg.net\/blog\/#\/schema\/person\/335af7b18e8e13d0ea182a6959e3cd71","name":"TK Comunica\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/ebfca77cb195b9e897fac15a333836ddc82752dc4be91c0f419de3d3daf543b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ebfca77cb195b9e897fac15a333836ddc82752dc4be91c0f419de3d3daf543b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ebfca77cb195b9e897fac15a333836ddc82752dc4be91c0f419de3d3daf543b4?s=96&d=mm&r=g","caption":"TK Comunica\u00e7\u00e3o"},"url":"https:\/\/museuweg.net\/blog\/author\/tkcomunicacao\/"}]}},"views":2452,"_links":{"self":[{"href":"https:\/\/museuweg.net\/blog\/wp-json\/wp\/v2\/posts\/1343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/museuweg.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/museuweg.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/museuweg.net\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/museuweg.net\/blog\/wp-json\/wp\/v2\/comments?post=1343"}],"version-history":[{"count":2,"href":"https:\/\/museuweg.net\/blog\/wp-json\/wp\/v2\/posts\/1343\/revisions"}],"predecessor-version":[{"id":1574,"href":"https:\/\/museuweg.net\/blog\/wp-json\/wp\/v2\/posts\/1343\/revisions\/1574"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/museuweg.net\/blog\/wp-json\/wp\/v2\/media\/1578"}],"wp:attachment":[{"href":"https:\/\/museuweg.net\/blog\/wp-json\/wp\/v2\/media?parent=1343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/museuweg.net\/blog\/wp-json\/wp\/v2\/categories?post=1343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/museuweg.net\/blog\/wp-json\/wp\/v2\/tags?post=1343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}